{"id":839,"date":"2022-03-22T19:18:26","date_gmt":"2022-03-22T18:18:26","guid":{"rendered":"https:\/\/velo-paysdelaloire.fr\/?p=839"},"modified":"2025-04-23T15:19:57","modified_gmt":"2025-04-23T13:19:57","slug":"16-22-mai-boostez-le-velo-sur-votre-lieu-de-travail-a-loccasion-du-defi-mobilite","status":"publish","type":"post","link":"https:\/\/velo-pdl.fr\/index.php\/2022\/03\/22\/16-22-mai-boostez-le-velo-sur-votre-lieu-de-travail-a-loccasion-du-defi-mobilite\/","title":{"rendered":"16-22 Mai : Boostez le v\u00e9lo sur votre lieu de travail \u00e0 l&rsquo;occasion du D\u00e9fi Mobilit\u00e9"},"content":{"rendered":"<p><strong>Boostez le v\u00e9lo gr\u00e2ce \u00e0 des animations et des financements !<\/strong><\/p>\n<p>Le <a href=\"https:\/\/www.defimobilite-paysdelaloire.fr\/\">D\u00e9fi Mobilit\u00e9<\/a> est le rendez-vous annuel mis en place par l&rsquo;ADEME et la R\u00e9gion Pays de la Loire pour passer \u00e0 l&rsquo;\u00e9co-mobilit\u00e9 sur nos lieux de travail ! Consultez le programme sur https:\/\/www.defimobilite-paysdelaloire.fr\/ <\/p>\n<p>L\u2019id\u00e9e est de faire un maximum de d\u00e9placements domicile-travail autrement qu&rsquo;en voiture individuelle sur cette p\u00e9riode, pour se prouver collectivement que cela est possible&#8230; avec \u00e9videmment l&rsquo;ambition de prolonger la d\u00e9marche au del\u00e0 !<\/p>\n<p>Et parmi les options, le v\u00e9lo est \u00e9videmment \u00e0 l&rsquo;honneur : il s&rsquo;agit d&rsquo;un mode de d\u00e9placement efficace et peu co\u00fbteux (\u00e0 l&rsquo;heure de la hausse des prix des carburant, c&rsquo;est non-n\u00e9gligeable !), bon pour la sant\u00e9 et l\u2019environnement, qui favorise le lien social, l\u2019emploi, l\u2019attractivit\u00e9 et le dynamisme \u00e9conomique des territoires tout en contribuant \u00e0 une am\u00e9lioration du cadre de vie\u2026. mais aussi \u00e0 l&rsquo;image de l&rsquo;entreprise (ou de l&rsquo;administration) et la qualit\u00e9 de vie au travail !<\/p>\n<p>Le Collectif vous propose deux solutions pour booster la pratique du v\u00e9lo \u00e0 l\u2019occasion du d\u00e9fi mobilit\u00e9.<\/p>\n<p><em><strong>1 &#8211; Contactez vite les associations pour animer votre d\u00e9fi !<\/strong><\/em><br \/>\nPlusieurs possibilit\u00e9s existent en fonction de vos besoins :<br \/>\n&#8211;\tSensibilisation \u00e0 la s\u00e9curit\u00e9 \u00e0 v\u00e9lo et Code de la route vu du guidon<br \/>\n&#8211;\tSession d\u00e9couverte de v\u00e9los sp\u00e9ciaux<br \/>\n&#8211;\tAteliers pour entretien \/ r\u00e9paration de v\u00e9los<br \/>\n&#8211;\tCours de v\u00e9lo (perfectionnement, d\u00e9butants, v\u00e9lo \u00e0 assistance \u00e9lectrique\u2026)<br \/>\n&#8211;\tD\u00e9couverte du territoire \u00e0 v\u00e9lo<br \/>\n&#8211;\tMarquage Bicycode contre le recel et le vol de v\u00e9lo<\/p>\n<p><a href=\"https:\/\/velo-paysdelaloire.fr\/index.php\/associations-membres\/\">Retrouvez ici<\/a> l\u2019association la plus proche de votre site pour planifier une animation \u00e0 l\u2019occasion du D\u00e9fi Mobilit\u00e9. <\/p>\n<p><em><strong>2- Vous ne savez pas par o\u00f9 commencer ou ne disposez pas d\u2019un budget \u00e0 la hauteur de vos ambitions sur le d\u00e9ploiement du v\u00e9lo ? N\u2019h\u00e9sitez pas \u00e0 \u00e0 tester (c\u2019est gratuit !) le programme national <a href=\"https:\/\/employeurprovelo.fr\/\">Objectif Employeur Pro-V\u00e9lo<\/a> : conseil sans engagement et financements attendent encore jusqu\u2019en 2023 au plus tard !<\/strong><\/em><\/p>\n<p>Ce programme vous permet notamment de b\u00e9n\u00e9ficier de financements pour faire intervenir des prestataires (dont des associations du Collectif V\u00e9lo Pays de la Loire) pour de la sensibilisation, des cours de v\u00e9lo, des ateliers m\u00e9canique v\u00e9lo etc. mais aussi d\u2019avoir un coup de pouce sur l\u2019installation de stationnement, des prestations de conseil pour votre plan mobilit\u00e9, etc. !<\/p>\n<p>A la cl\u00e9 de vos efforts si vous poursuivez la d\u00e9marche jusqu\u2019au bout : un audit pour faire reconnaitre votre qualit\u00e9 d\u2019employeur pro-v\u00e9lo gr\u00e2ce \u00e0 un label : d\u00e9j\u00e0 300 employeurs se sont lanc\u00e9s dans l\u2019aventure, pourquoi pas vous ?<\/p>\n<p><a href=\"https:\/\/www.defimobilite-paysdelaloire.fr\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/velo-paysdelaloire.fr\/wp-content\/uploads\/2022\/03\/bandeau-defi-mobilite-pays-de-la-loire-2022.png\" alt=\"\" width=\"1119\" height=\"388\" class=\"aligncenter size-full wp-image-841\" srcset=\"https:\/\/velo-pdl.fr\/wp-content\/uploads\/2022\/03\/bandeau-defi-mobilite-pays-de-la-loire-2022.png 1119w, https:\/\/velo-pdl.fr\/wp-content\/uploads\/2022\/03\/bandeau-defi-mobilite-pays-de-la-loire-2022-300x104.png 300w, https:\/\/velo-pdl.fr\/wp-content\/uploads\/2022\/03\/bandeau-defi-mobilite-pays-de-la-loire-2022-1024x355.png 1024w, https:\/\/velo-pdl.fr\/wp-content\/uploads\/2022\/03\/bandeau-defi-mobilite-pays-de-la-loire-2022-768x266.png 768w\" sizes=\"auto, (max-width: 1119px) 100vw, 1119px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boostez le v\u00e9lo gr\u00e2ce \u00e0 des animations et des financements ! Le D\u00e9fi Mobilit\u00e9 est le rendez-vous annuel mis en place par l&rsquo;ADEME et la R\u00e9gion Pays de la Loire [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":841,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7,3,5,6,8,4,9],"class_list":["post-839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe","tag-challenge-mobilite","tag-defi-mobilite","tag-domicile-travail","tag-pays-de-la-loire","tag-solution-velo","tag-velo","tag-velotaf"],"_links":{"self":[{"href":"https:\/\/velo-pdl.fr\/index.php\/wp-json\/wp\/v2\/posts\/839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/velo-pdl.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/velo-pdl.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/velo-pdl.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/velo-pdl.fr\/index.php\/wp-json\/wp\/v2\/comments?post=839"}],"version-history":[{"count":5,"href":"https:\/\/velo-pdl.fr\/index.php\/wp-json\/wp\/v2\/posts\/839\/revisions"}],"predecessor-version":[{"id":845,"href":"https:\/\/velo-pdl.fr\/index.php\/wp-json\/wp\/v2\/posts\/839\/revisions\/845"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/velo-pdl.fr\/index.php\/wp-json\/wp\/v2\/media\/841"}],"wp:attachment":[{"href":"https:\/\/velo-pdl.fr\/index.php\/wp-json\/wp\/v2\/media?parent=839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/velo-pdl.fr\/index.php\/wp-json\/wp\/v2\/categories?post=839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/velo-pdl.fr\/index.php\/wp-json\/wp\/v2\/tags?post=839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}